{"id":565,"count":313,"description":"","link":"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/","name":"Fryske produkten","slug":"friese-producten","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":140,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fryske produkten &#8211; Af\u00fbk Websjop<\/title>\n<meta name=\"description\" content=\"Zoek je een typisch Fries cadeautje? Of wil je een leuk Fries kaartje sturen? De Af\u00fbk heeft een ruim aanbod aan Friese producten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fryske produkten &#8211; Af\u00fbk Websjop\" \/>\n<meta property=\"og:description\" content=\"Zoek je een typisch Fries cadeautje? Of wil je een leuk Fries kaartje sturen? De Af\u00fbk heeft een ruim aanbod aan Friese producten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/\" \/>\n<meta property=\"og:site_name\" content=\"Af\u00fbk Websjop\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/producten\\\/friese-producten\\\/\",\"url\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/producten\\\/friese-producten\\\/\",\"name\":\"Fryske produkten &#8211; Af\u00fbk Websjop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/#website\"},\"description\":\"Zoek je een typisch Fries cadeautje? Of wil je een leuk Fries kaartje sturen? De Af\u00fbk heeft een ruim aanbod aan Friese producten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/producten\\\/friese-producten\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/producten\\\/friese-producten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fryske produkten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/\",\"name\":\"Af\u00fbk Websjop\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/websjop.afuk.frl\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fryske produkten &#8211; Af\u00fbk Websjop","description":"Zoek je een typisch Fries cadeautje? Of wil je een leuk Fries kaartje sturen? De Af\u00fbk heeft een ruim aanbod aan Friese producten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/","og_locale":"nl_NL","og_type":"article","og_title":"Fryske produkten &#8211; Af\u00fbk Websjop","og_description":"Zoek je een typisch Fries cadeautje? Of wil je een leuk Fries kaartje sturen? De Af\u00fbk heeft een ruim aanbod aan Friese producten.","og_url":"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/","og_site_name":"Af\u00fbk Websjop","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/","url":"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/","name":"Fryske produkten &#8211; Af\u00fbk Websjop","isPartOf":{"@id":"https:\/\/websjop.afuk.frl\/nl\/#website"},"description":"Zoek je een typisch Fries cadeautje? Of wil je een leuk Fries kaartje sturen? De Af\u00fbk heeft een ruim aanbod aan Friese producten.","breadcrumb":{"@id":"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/websjop.afuk.frl\/nl\/producten\/friese-producten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/websjop.afuk.frl\/nl\/"},{"@type":"ListItem","position":2,"name":"Fryske produkten"}]},{"@type":"WebSite","@id":"https:\/\/websjop.afuk.frl\/nl\/#website","url":"https:\/\/websjop.afuk.frl\/nl\/","name":"Af\u00fbk Websjop","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/websjop.afuk.frl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/websjop.afuk.frl\/nl\/wp-json\/wp\/v2\/product_cat\/565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/websjop.afuk.frl\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/websjop.afuk.frl\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/websjop.afuk.frl\/nl\/wp-json\/wp\/v2\/product?product_cat=565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}